{"id":1021,"count":1,"description":"","link":"https:\/\/www.soymedicina.com\/libros-de-medicina\/tag\/manual-washington-de-ecocardiografia\/","name":"Manual Washington de Ecocardiograf\u00eda","slug":"manual-washington-de-ecocardiografia","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/tags\/1021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/posts?tags=1021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}