{"id":27126,"date":"2023-02-03T01:51:39","date_gmt":"2023-02-03T01:51:39","guid":{"rendered":"https:\/\/www.soymedicina.com\/libros-de-medicina\/?p=27126"},"modified":"2024-02-17T03:18:10","modified_gmt":"2024-02-17T03:18:10","slug":"fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas-2-edicion","status":"publish","type":"post","link":"https:\/\/www.soymedicina.com\/libros-de-medicina\/fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas-2-edicion\/","title":{"rendered":"Fundamentos de Medicina Radiolog\u00eda e Im\u00e1genes Diagn\u00f3sticas &#8211; 2 Edicion"},"content":{"rendered":"<p style=\"text-align: justify;\">El Fondo Editorial de la Corporaci\u00f3n para Investigaciones Biol\u00f3gicas (CIB) presenta con orgullo la segunda edici\u00f3n del texto Radiolog\u00eda e Im\u00e1genes Diagn\u00f3sticas, editado por los Doctores Juan Esteban Guti\u00e9rrez, Rodrigo Restrepo y Jorge Andr\u00e9s Soto, con la destacada colaboraci\u00f3n del Dr. Jos\u00e9 Luis Criales-Cort\u00e9s como editor invitado de M\u00e9xico. Los editores tuvieron el acierto de reunir a connotados especialistas de Colombia, Estados Unidos, M\u00e9xico y Argentina para colaborar en la preparaci\u00f3n de esta obra. Por consiguiente, el texto refleja las tendencias mundiales y ofrece un panorama amplio del respectivo conocimiento. La pluralidad de autores y de subespecialidades hizo necesaria la actualizaci\u00f3n de todos los cap\u00edtulos, as\u00ed como la inclusi\u00f3n de 13 nuevos t\u00f3picos, todo lo cual hace de esta segunda edici\u00f3n, un texto totalmente renovado.<\/p>\n<div class=\"mks_toggle\">\r\n            <div class=\"mks_toggle_heading\">Tabla de Contenido<i class=\"fa fa-plus\"><\/i><i class=\"fa fa-minus\"><\/i><\/div>\r\n                <div class=\"mks_toggle_content\">\n<p>Unidad I \u2013 Generalidades Historia de la Radiolog\u00eda Principios F\u00edsicos y T\u00e9cnicos de las Im\u00e1genes M\u00e9dicas Principios Generales para la Interpretaci\u00f3n de las Im\u00e1genes M\u00e9dicas. Medios de Contraste<br \/>\nUnidad II \u2013 Cabeza y Cuello Enfermedades Cong\u00e9nitas Cerebrales Im\u00e1gen en Isquemia Cerebral Aguda, Enfermedades Infecciosas Cerebrales. Enfermedades Neurodegenerativas Tumores Intracraneales Orbita O\u00eddo: Estudio por Im\u00e1genes Senos Paranasales: Evaluaci\u00f3n por Im\u00e1genes Articulaci\u00f3n Temporomandibular: Estudio por Im\u00e1genes Cuello, Gl\u00e1ndulas Salivares y Gl\u00e1ndula Tiroides Malformaciones Vasculares de Cabeza y Cuello y su Tratamiento Endovascular<br \/>\nUnidad III \u2013 Columna Vertebral Malformaciones Cong\u00e9nitas de la Columna Vertebral Tumores y Masas Espinales Patolog\u00eda Vertebral Inflamatoria e Infecciosa Enfermedad Degenerativa de la Columna<br \/>\nUnidad IV- T\u00f3rax Patrones Pulmonares en Radiograf\u00eda Simple y Tomograf\u00eda Computarizada Infecciones Pulmonares Enfermedad Pulmonar Infiltrativa Difusa Cr\u00f3nica Tromboembolia Pulmonar: M\u00e9todos de Imagen Enfermedad Pulmonar Obstructiva Cr\u00f3nica, Bronquiectasias y Asma. Toxicidad Pulmonar por Medicamentos Carcinoma Broncog\u00e9nico: M\u00e9todos de Diagn\u00f3stico por Imagen Estudios por Im\u00e1genes en Insuficiencia Card\u00edaca Evaluaci\u00f3n por Im\u00e1genes del Coraz\u00f3n y Grandes Vasos del Adulto Enfermedades de la Pleura, Pared Tor\u00e1cica, Diafragma y Mediastino.<br \/>\nUnidad V \u2013 Abdomen Tracto Gastrointestinal Enfermedades del H\u00edgado, P\u00e1ncreas, Bazo y Conductos Biliares Ri\u00f1\u00f3n, V\u00edas Urinarias y Retroperitoneo Abdomen Agudo Pelvis Masculina: Evaluaci\u00f3n por Ecograf\u00eda. Pelvis Femenina: Evaluaci\u00f3n por Ecograf\u00eda Evaluaci\u00f3n de la Pelvis Mediante Tomograf\u00eda Computarizada y Resonancia Magn\u00e9tica<br \/>\nUnidad VI \u2013 Sistema Osteomuscular Caracter\u00edsticas Radiol\u00f3gicas de las Enfermedades Articulares Lesiones Osteoarticulares Enfermedades Infecciosas del Sistema Osteomuscular Tumores Oseos Ultrasonido Musculoesquel\u00e9tico<br \/>\nUnidad VII \u2013 Intervencionismo y Doppler Intervencionismo en T\u00f3rax y Abdomen Angiograf\u00eda e Intervencionismo Vascular Perif\u00e9rico Ultrasonido Vascular Perif\u00e9rico (Doppler)<br \/>\nUnidad VIII \u2013 Trauma Traumatismo Craneoencef\u00e1lico y Facial Traumatismo de T\u00f3rax Traumatismo Abdominal Traumatismo Raquimedular y de Columna Cervical Trauma del Sistema Musculoesquel\u00e9tico y Lesiones Deportivas<br \/>\nUnidad IX \u2013 Radiolog\u00eda de la Mujer Mamograf\u00eda Ecograf\u00eda de Mama Resonancia Magn\u00e9tica de la Mama Ecograf\u00eda del Embarazo Normal Embarazo Anormal Evaluaci\u00f3n de la Infertilidad Mediante Im\u00e1genes Diagn\u00f3sticas<br \/>\nUnidad X \u2013 Pediatr\u00eda Estudio del T\u00f3rax en Pediatr\u00eda Malformaciones Pulmonares Enfermedades del Tracto Gastrointestinal en Pediatr\u00eda Sistema Genitourinario y Retroperitoneo en Pediatr\u00eda Sistema Musculoesquel\u00e9tico en Pediatr\u00eda<br \/>\nUnidad XI \u2013 Medicina Nuclear Medicina Nuclear<\/p>\n<\/div>\r\n            <\/div>\n<div class=\"mks_toggle mks_toggle_active\">\r\n            <div class=\"mks_toggle_heading\">Detalles eBook<i class=\"fa fa-plus\"><\/i><i class=\"fa fa-minus\"><\/i><\/div>\r\n                <div class=\"mks_toggle_content\">\n<p>ISBN: 9589400795<br \/>\nA\u00f1o de publicacion: 2004<br \/>\nAutores: Hern\u00e1n V\u00e9lez, William Rojas, Jaime Borrero, Jorge Restrepo<br \/>\nNumero de paginas: 632<br \/>\nIdioma: Espa\u00f1ol<br \/>\nFormato: PDF<\/p>\n<\/div>\r\n            <\/div>\n<div class=\"mks_toggle\">\r\n            <div class=\"mks_toggle_heading\">Links de Descarga<i class=\"fa fa-plus\"><\/i><i class=\"fa fa-minus\"><\/i><\/div>\r\n                <div class=\"mks_toggle_content\">\n<p style=\"text-align: center;\"><a href=\"https:\/\/drive.google.com\/file\/d\/14qPA0785OWSse4EGZ8PX6_-ZBpwDIUrE\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\">Google Drive<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.mediafire.com\/file\/mu7wp9zp4d6wdpo\/160224FMRID2.rar\/file\" target=\"_blank\" rel=\"noopener\">MediaFire<\/a><\/p>\n<\/div>\r\n            <\/div>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>El Fondo Editorial de la Corporaci\u00f3n para Investigaciones Biol\u00f3gicas (CIB) presenta con orgullo la segunda edici\u00f3n del texto Radiolog\u00eda e Im\u00e1genes Diagn\u00f3sticas, editado por los Doctores Juan Esteban Guti\u00e9rrez, Rodrigo Restrepo y Jorge Andr\u00e9s Soto, con la destacada colaboraci\u00f3n del Dr. Jos\u00e9 Luis Criales-Cort\u00e9s como editor invitado de M\u00e9xico. Los editores tuvieron el acierto de reunir a connotados especialistas de<\/p>\n<div class=\"h10\"><\/div>\n<p><a class=\"more-link2 flat\" href=\"https:\/\/www.soymedicina.com\/libros-de-medicina\/fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas-2-edicion\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":27127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[1502,1499,1501,1500,1505,1504,1503],"class_list":["post-27126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-radiologia-e-imagenologia","tag-fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas","tag-fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas-2-edicion","tag-fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas-2-edicion-descargar-gratis","tag-fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas-2-edicion-pdf","tag-fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas-descargar-pdf","tag-fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas-libro-gratis","tag-fundamentos-de-medicina-radiologia-e-imagenes-diagnosticas-pdf"],"rttpg_featured_image_url":{"full":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",750,1065,false],"landscape":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",750,1065,false],"portraits":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",750,1065,false],"thumbnail":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",68,96,false],"medium":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",750,1065,false],"large":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",750,1065,false],"RoboGalleryMansoryImagesCenter":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",600,852,false],"RoboGalleryPreload":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",100,142,false],"1536x1536":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",750,1065,false],"2048x2048":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",750,1065,false],"boc_thumb":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia-150x150.jpg",150,150,true],"boc_medium":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia-600x380.jpg",600,380,true],"boc_thin":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia-750x600.jpg",750,600,true],"bloom_image":["https:\/\/soymedicina.b-cdn.net\/libros-de-medicina\/wp-content\/uploads\/Radiologia.jpg",610,866,false]},"rttpg_author":{"display_name":"Administrador","author_link":"https:\/\/www.soymedicina.com\/libros-de-medicina\/author\/administrador\/"},"rttpg_comment":1,"rttpg_category":"<a href=\"https:\/\/www.soymedicina.com\/libros-de-medicina\/categoria-articulo\/radiologia-e-imagenologia\/\" rel=\"category tag\">Radiolog\u00eda e Imagenologia<\/a>","rttpg_excerpt":"El Fondo Editorial de la Corporaci\u00f3n para Investigaciones Biol\u00f3gicas (CIB) presenta con orgullo la segunda edici\u00f3n del texto Radiolog\u00eda e Im\u00e1genes Diagn\u00f3sticas, editado por los Doctores Juan Esteban Guti\u00e9rrez, Rodrigo Restrepo y Jorge Andr\u00e9s Soto, con la destacada colaboraci\u00f3n del Dr. Jos\u00e9 Luis Criales-Cort\u00e9s como editor invitado de M\u00e9xico. Los editores tuvieron el acierto de&hellip;","_links":{"self":[{"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/posts\/27126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/comments?post=27126"}],"version-history":[{"count":2,"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/posts\/27126\/revisions"}],"predecessor-version":[{"id":27766,"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/posts\/27126\/revisions\/27766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/media\/27127"}],"wp:attachment":[{"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/media?parent=27126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/categories?post=27126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.soymedicina.com\/libros-de-medicina\/wp-json\/wp\/v2\/tags?post=27126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}